{"id":3383,"date":"2024-10-24T14:23:40","date_gmt":"2024-10-24T12:23:40","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/dromeardeche\/?p=3383"},"modified":"2024-11-11T14:19:21","modified_gmt":"2024-11-11T13:19:21","slug":"coupe-championnat-p-b-m-c-j-s-kata-et-kumite","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/dromeardeche\/2024\/10\/24\/coupe-championnat-p-b-m-c-j-s-kata-et-kumite\/","title":{"rendered":"Coupe &amp; championnat P.B \/\/ M.C.J.S kata et kumit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p class=\"gmail-default\" style=\"margin: 0cm 0cm 1.5pt 0cm\"><span style=\"color: black\">Les 2 comp\u00e9titions kata &amp; kumit\u00e9 se d\u00e9rouleront sur toute la journ\u00e9e pour toutes les cat\u00e9gories,<\/span><\/p>\n<p>Depuis cette saison, les inscriptions aux comp\u00e9titions sont payantes 3\u20ac\/licenci\u00e9, \u00e0 r\u00e9gler sur le site lors de l&rsquo;inscriptions de vos comp\u00e9titeurs<\/p>\n<p>&nbsp;<\/p>\n<p class=\"gmail-default\" style=\"margin: 0cm 0cm 1.5pt 0cm\"><span style=\"color: black\">Le matin : M.C.J.S kata et kumit\u00e9<\/span><\/p>\n<p class=\"gmail-default\" style=\"margin: 0cm 0cm 1.5pt 0cm\"><span style=\"color: black\">L\u2019apr\u00e8s-midi\u00a0: P.B kata et kumit\u00e9<\/span><\/p>\n<p>Lien inscription\u00a0: https:\/\/www.ffkcompetition.fr\/<\/p>\n<p>Date butoir au plus tard le mardi 14 novembre 2024, dernier d\u00e9lai.<\/p>\n<p>Lieu\u00a0: \u00a0<strong><em><u>Maison\u00a0des sports J<\/u><\/em><\/strong><strong><em><u>ean Monpeyssen, <\/u><\/em><\/strong><strong><em><u>salle multisports<\/u><\/em><\/strong><\/p>\n<p>Inscriptions et paiement en ligne, nouvelle interface.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-3384\" src=\"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-content\/uploads\/sites\/40\/2024\/10\/Tuto-300x96.png\" alt=\"\" width=\"606\" height=\"194\" srcset=\"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-content\/uploads\/sites\/40\/2024\/10\/Tuto-300x96.png 300w, https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-content\/uploads\/sites\/40\/2024\/10\/Tuto-1024x327.png 1024w, https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-content\/uploads\/sites\/40\/2024\/10\/Tuto-768x245.png 768w, https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-content\/uploads\/sites\/40\/2024\/10\/Tuto.png 1199w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/>114, promenade de la digue 26110 Nyons[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Les 2 comp\u00e9titions kata &amp; kumit\u00e9 se d\u00e9rouleront sur toute la journ\u00e9e pour toutes les cat\u00e9gories, Depuis cette saison, les inscriptions aux comp\u00e9titions sont payantes 3\u20ac\/licenci\u00e9, \u00e0 r\u00e9gler sur le site lors de l&rsquo;inscriptions de vos comp\u00e9titeurs &nbsp; Le matin : M.C.J.S kata et kumit\u00e9 L\u2019apr\u00e8s-midi\u00a0: P.B kata et kumit\u00e9 Lien inscription\u00a0: https:\/\/www.ffkcompetition.fr\/ Date [&hellip;]<\/p>\n","protected":false},"author":198,"featured_media":3391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3383","post","type-post","status-publish","format-standard","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/posts\/3383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/users\/198"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/comments?post=3383"}],"version-history":[{"count":8,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/posts\/3383\/revisions"}],"predecessor-version":[{"id":3419,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/posts\/3383\/revisions\/3419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/media\/3391"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/media?parent=3383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/categories?post=3383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/dromeardeche\/wp-json\/wp\/v2\/tags?post=3383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}