{"id":50,"date":"2015-07-01T09:31:53","date_gmt":"2015-07-01T07:31:53","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/testclone\/?page_id=50"},"modified":"2015-07-01T09:31:53","modified_gmt":"2015-07-01T07:31:53","slug":"le-comite","status":"publish","type":"page","link":"https:\/\/sites.ffkarate.fr\/hautegaronne\/le-comite\/","title":{"rendered":"Le Comit\u00e9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Bienvenue sur le site officiel du Comit\u00e9 d\u00e9partemental !<\/p>\n<p>Vous trouverez sur ce site toute l&rsquo;actualit\u00e9 du karat\u00e9 et de ses disciplines associ\u00e9es :<br \/>\n<a href=\"https:\/\/sites.ffkarate.fr\/hautegaronne\/calendrier-cdk-haute-garonne\/\">le calendrier <\/a>des diff\u00e9rentes comp\u00e9titions, passage de grade 1er et 2\u00e8me Dan, stages et autres\u00a0 manifestations, mais aussi toutes les informations et documents n\u00e9cessaires aux dirigeants de club ainsi qu&rsquo;aux licenci\u00e9(e)s.<\/p>\n<p>Bonne visite.<\/p>\n<p>&nbsp;<\/p>\n<h2>Nos coordonn\u00e9es<\/h2>\n<p><strong>Comit\u00e9 D\u00e9partemental de Karat\u00e9 &amp;\u00a0<\/strong><strong>Disciplines Associ\u00e9es de la Haute-Garonne<\/strong><\/p>\n<p>7, rue Andr\u00e9 Citro\u00ebn<\/p>\n<p>31130 BALMA<\/p>\n<p>T\u00e9l : <strong>05 61 58 34 31<\/strong><br \/>\nE-mail : <a href=\"mailto:cdkda31@ffkarate.fr\" rel=\"noreferrer\">cdkda31@ffkarate.fr<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Bienvenue sur le site officiel du Comit\u00e9 d\u00e9partemental ! Vous trouverez sur ce site toute l&rsquo;actualit\u00e9 du karat\u00e9 et de ses disciplines associ\u00e9es : le calendrier des diff\u00e9rentes comp\u00e9titions, passage de grade 1er et 2\u00e8me Dan, stages et autres\u00a0 manifestations, mais aussi toutes les informations et documents n\u00e9cessaires aux dirigeants de club ainsi qu&rsquo;aux licenci\u00e9(e)s. [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":1137,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-50","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/pages\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/pages\/50\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/media\/1137"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/hautegaronne\/wp-json\/wp\/v2\/media?parent=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}