{"id":647,"date":"2022-01-07T17:43:08","date_gmt":"2022-01-07T16:43:08","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/hautemarne\/?p=647"},"modified":"2022-02-10T11:41:08","modified_gmt":"2022-02-10T10:41:08","slug":"le-club-fight-camp","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/hautemarne\/2022\/01\/07\/le-club-fight-camp\/","title":{"rendered":"Vie des Clubs &#8211; Fight Camp Saint-Dizier"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Fight Camp est un club ouvert depuis le 4 <span id=\"OBJ_PREFIX_DWT130_com_zimbra_date\" class=\"Object\">septembre 2019 et<\/span>\u00a0propose un large panel de disciplines : la boxe tha\u00eflandaise, la lutte, le Grappling, le MMA, le Sanda et le Kung-fu. L\u2019objectif initial du club \u00e9tait de proposer et de former nos adh\u00e9rents \u00e0 une multitude de disciplines afin qu\u2019ils soient polyvalents. Les cours sont ouverts tous les jours de la semaine, proposant chaque jour une discipline diff\u00e9rente et des cr\u00e9neaux d\u2019\u00e2ge diff\u00e9rent. Certains cr\u00e9neaux le week-end sont verrouill\u00e9s pour les comp\u00e9titeurs et les combattants professionnels ou semi-professionnel.<\/p>\n<p>R\u00e9cemment des licenci\u00e9s se sont illustr\u00e9s par plusieurs podiums sur plusieurs comp\u00e9titions\u00a0dont la Coupe de France de Karat\u00e9 Mixte qui correspond \u00e0 la vision de recherche en polyvalence. Notamment, Amine Bedoui en light chez les -66 kilos par la 1\u00e8re place, Letchi Gadaev en -61 kilos s\u2019offre \u00e9galement la 1\u00e8re place, cette fois-ci en Contact. Alkazhur finira 2\u00e8me apr\u00e8s une belle s\u00e9rie de KO.<\/p>\n<p>Letchi Gadaev est initialement un combattant de boxe tha\u00eflandaise et de kick boxing. Depuis quelques mois, avec son fr\u00e8re Alkazhur, ils ont d\u00e9cid\u00e9s de faire une transition en MMA et Karat\u00e9 Mix. Amine Bedoui est lui initialement issu de la lutte et du Grappling.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_gallery images=\u00a0\u00bb648,649&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Fight Camp est un club ouvert depuis le 4 septembre 2019 et\u00a0propose un large panel de disciplines : la boxe tha\u00eflandaise, la lutte, le Grappling, le MMA, le Sanda et le Kung-fu. L\u2019objectif initial du club \u00e9tait de proposer et de former nos adh\u00e9rents \u00e0 une multitude de disciplines afin qu\u2019ils soient polyvalents. Les cours [&hellip;]<\/p>\n","protected":false},"author":211,"featured_media":650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10,15,16,18],"tags":[],"class_list":["post-647","post","type-post","status-publish","format-standard","hentry","category-actualites","category-competitions","category-k-full-contact","category-karate-mix","category-vie-des-clubs"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/posts\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/users\/211"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/comments?post=647"}],"version-history":[{"count":5,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/posts\/647\/revisions"}],"predecessor-version":[{"id":728,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/posts\/647\/revisions\/728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/media\/650"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/media?parent=647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/categories?post=647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautemarne\/wp-json\/wp\/v2\/tags?post=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}