{"id":4628,"date":"2022-12-29T08:41:33","date_gmt":"2022-12-29T07:41:33","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/?p=4628"},"modified":"2022-12-29T08:41:33","modified_gmt":"2022-12-29T07:41:33","slug":"stage-k-mix-a-haisnes","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/2022\/12\/29\/stage-k-mix-a-haisnes\/","title":{"rendered":"Stage K-MIX \u00e0 Haisnes"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]La commission K-MIX Ligue HDF organise un stage le samedi 28 janvier 2023 de 14h \u00e0 17h \u00e0 Haisnes.<\/p>\n<p>Le stage est ouvert aux licenci\u00e9s FFK \u00e0 partir de 12 ans et sera dirig\u00e9 en collaboration par Serge CAL, Ludovic DECAMPS et Fran\u00e7ois HOUDART<\/p>\n<p>Au programme:<\/p>\n<ul>\n<li>Stage Technique K-Mix<\/li>\n<li>Pr\u00e9paration aux examens de grades K-Mix<\/li>\n<li>Arbitrage K-Mix<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]La commission K-MIX Ligue HDF organise un stage le samedi 28 janvier 2023 de 14h \u00e0 17h \u00e0 Haisnes. Le stage est ouvert aux licenci\u00e9s FFK \u00e0 partir de 12 ans et sera dirig\u00e9 en collaboration par Serge CAL, Ludovic DECAMPS et Fran\u00e7ois HOUDART Au programme: Stage Technique K-Mix Pr\u00e9paration aux examens de grades K-Mix [&hellip;]<\/p>\n","protected":false},"author":161,"featured_media":4633,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-4628","post","type-post","status-publish","format-standard","hentry","category-stages"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/posts\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/comments?post=4628"}],"version-history":[{"count":3,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/posts\/4628\/revisions"}],"predecessor-version":[{"id":4631,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/posts\/4628\/revisions\/4631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/media\/4633"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/media?parent=4628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/categories?post=4628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/hautsdefrance\/wp-json\/wp\/v2\/tags?post=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}