{"id":4009,"date":"2025-07-14T17:43:18","date_gmt":"2025-07-14T15:43:18","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/nord\/?p=4009"},"modified":"2025-07-14T17:50:43","modified_gmt":"2025-07-14T15:50:43","slug":"resultats-jeux-mondiaux-police-2025-alex-lemille-vice-champion-du-monde","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/nord\/2025\/07\/14\/resultats-jeux-mondiaux-police-2025-alex-lemille-vice-champion-du-monde\/","title":{"rendered":"RESULTATS JEUX MONDIAUX POLICE 2025: ALEX LEMILLE VICE-CHAMPION du MONDE."},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center\">BIRMINGHAM: DU 27 JUIN AU 6 JUILLET 2025.<\/h2>\n<h1 style=\"text-align: center\">Alex LEMILLE : un Karat\u00e9ka d\u2019exception au service de la Police et du sport.<\/h1>\n<div class=\"video_article\"><\/div>\n<p>Depuis 2017, Alex LEMILLE est affect\u00e9 au SIPAF59, le Service Interd\u00e9partemental de la Police Aux Fronti\u00e8res dans le Nord. Mais cet agent ne se distingue pas seulement par son engagement professionnel : passionn\u00e9 de karat\u00e9 depuis 1996,<\/p>\n<p>En parall\u00e8le de son r\u00f4le au sein des forces de l\u2019ordre, Alex excelle \u00e9galement sur les tatamis en tant que comp\u00e9titeur de haut niveau.<\/p>\n<p>Les performances d\u2019Alex LEMILLE brillent \u00e0 l\u2019international, notamment lors des Championnats Europ\u00e9ens des Forces de S\u00e9curit\u00e9. En octobre 2023, \u00e0 Torrevieja, en Espagne, il d\u00e9croche deux titres majeurs : celui de vice-champion d\u2019Europe en individuel et de champion d\u2019Europe par \u00e9quipe.<\/p>\n<p>Un an plus tard, du 16 au 20 octobre 2024, \u00e0 Braga, au Portugal, lors du Championnat Europ\u00e9en des Forces de S\u00e9curit\u00e9 Int\u00e9rieure r\u00e9unissant des participants de 22 nations, Alex frappe encore plus fort. Dans la cat\u00e9gorie -75 kg, il devient\u00a0<strong>champion d\u2019Europe individuel<\/strong>\u00a0et ajoute un titre de\u00a0<strong>vice-champion d\u2019Europe par \u00e9quipe<\/strong>\u00a0\u00e0 son palmar\u00e8s.<\/p>\n<p>Le parcours d\u2019Alex LEMILLE ne s\u2019arr\u00eate pas l\u00e0. En juillet 2025, il portera haut les couleurs de la France lors du Championnat du Monde des Forces de S\u00e9curit\u00e9, qui se tiendra en Alabama, aux \u00c9tats-Unis. Cet \u00e9v\u00e9nement promet d\u2019\u00eatre une nouvelle \u00e9tape marquante dans une carri\u00e8re d\u00e9j\u00e0 impressionnante.<\/p>\n<p>Alex LEMILLE incarne l\u2019alliance entre engagement professionnel et excellence sportive. Son parcours inspire et t\u00e9moigne de l\u2019importance de la discipline et de la pers\u00e9v\u00e9rance, des valeurs ch\u00e8res au karat\u00e9 et aux forces de l\u2019ordre.<\/p>\n<p><strong>Alex LEMILLE<\/strong> est fier d&rsquo;y avoir repr\u00e9sent\u00e9 la France, la R\u00e9gion et le D\u00e9partement du Nord et d\u2019y \u00eatre revenue avec les titres de <strong>Vice-Champion<\/strong> du <strong>Monde<\/strong> en individuel et de prendre la <strong>3\u00e8me place<\/strong> avec l\u2019\u00e9quipe de France en accrochant cette m\u00e9daille de bronze.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\">Toutes nos f\u00e9licitations \u00e0 Alex pour ces r\u00e9sultats.<\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-4016\" src=\"https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01-226x300.jpg\" alt=\"\" width=\"226\" height=\"300\" srcset=\"https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01-226x300.jpg 226w, https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01-771x1024.jpg 771w, https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01-768x1020.jpg 768w, https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01-1157x1536.jpg 1157w, https:\/\/sites.ffkarate.fr\/nord\/wp-content\/uploads\/sites\/81\/2025\/07\/Medaille-01.jpg 1204w\" sizes=\"(max-width: 226px) 100vw, 226px\" \/><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] BIRMINGHAM: DU 27 JUIN AU 6 JUILLET 2025. Alex LEMILLE : un Karat\u00e9ka d\u2019exception au service de la Police et du sport. Depuis 2017, Alex LEMILLE est affect\u00e9 au SIPAF59, le Service Interd\u00e9partemental de la Police Aux Fronti\u00e8res dans le Nord. Mais cet agent ne se distingue pas seulement par son engagement professionnel : [&hellip;]<\/p>\n","protected":false},"author":128,"featured_media":4015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,14],"tags":[],"class_list":["post-4009","post","type-post","status-publish","format-standard","hentry","category-competitions","category-karate"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/posts\/4009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/comments?post=4009"}],"version-history":[{"count":6,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/posts\/4009\/revisions"}],"predecessor-version":[{"id":4018,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/posts\/4009\/revisions\/4018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/media\/4015"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/media?parent=4009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/categories?post=4009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/nord\/wp-json\/wp\/v2\/tags?post=4009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}