{"id":2659,"date":"2019-02-08T16:19:42","date_gmt":"2019-02-08T15:19:42","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/normandie\/?post_type=news&amp;p=2659"},"modified":"2019-02-08T16:19:42","modified_gmt":"2019-02-08T15:19:42","slug":"competitions-de-mars-2019","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/normandie\/2019\/02\/08\/competitions-de-mars-2019\/","title":{"rendered":"Comp\u00e9titions de Mars 2019"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<img decoding=\"async\" src=\"https:\/\/sites.ffkarate.fr\/normandie\/wp-content\/uploads\/sites\/10\/2019\/02\/COMPETITION-KUMITE-NORMANDIE-PB-FORGES-02032019-150x150.png\" alt=\"COMPETITION-KUMITE-NORMANDIE-PB-FORGES-02032019\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-2660\" \/>Programmes des comp\u00e9titions pr\u00e9vues sur Mars 2019<\/p>\n<p>Le 02 Mars 2019 \u2013 Coupe de Normandie  Combat Elite\/Honneur Pupilles \/ Benjamins indiv.<br \/>\n&#8211; Inscription en Ligne uniquement : date limite le 28\/02\/2019<br \/>\n&#8211; Droit d\u2019inscription athl\u00e8te : joindre au r\u00e8glement (ch\u00e8que club), soit la copie de votre saisie sur l\u2019intranet OU le fichier excel ci-joint.<\/p>\n<p>Le 13 Mars 2019 \u2013 Championnat de Normandie Combat Minimes\/Cadet\/Juniors\/seniors indiv. Equipes.<br \/>\n&#8211; Inscription en Ligne uniquement : date limite le 28\/02\/2019<br \/>\n&#8211; Droit d\u2019inscription athl\u00e8te : joindre au r\u00e8glement (ch\u00e8que club), soit la copie de votre saisie sur l\u2019intranet OU le fichier excel ci-joint.<\/p>\n<p>Le 16 Mars 2019 \u2013 Opens de la Ligue de Normandie et Championnat de Normandie<br \/>\nOpen Combat\/Kata \u2013 Pupilles\/Benjamins \/ Championnat Kata \u2013 Minimes \u00e0 Seniors Indivi. et Equipes<br \/>\n&#8211; Inscription en Ligne uniquement : date limite le 28\/02\/2019 : date limite le 28\/02\/2019<br \/>\n&#8211; Droit d\u2019inscription athl\u00e8te : joindre au r\u00e8glement (ch\u00e8que club), soit la copie de votre saisie sur l\u2019intranet OU le fichier excel ci-joint.<br \/>\n( Un r\u00e8glement par inscription,  deux comp\u00e9titions = 2 droits d\u2019engagement)<\/p>\n<p>Le 17 Mars 2019 \u2013 Stage entra\u00eenement Kata De Pupilles \u00e0 Seniors<\/p>\n<p>A venir  :<br \/>\n&#8211; Le 02 Mars 2019 &#8211; Stage information grades Wushu<br \/>\n&#8211; Le 24 Mars 2019 &#8211; Challenge des 5 D\u00e9partements<\/p>\n<p>&#8211; Le 12 Mai 2019 &#8211; Examens Grades Wushu 1er, 2\u00e8me,3\u00e8me, 4\u00e8me et 5\u00e8me Duan[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Programmes des comp\u00e9titions pr\u00e9vues sur Mars 2019 Le 02 Mars 2019 \u2013 Coupe de Normandie Combat Elite\/Honneur Pupilles \/ Benjamins indiv. &#8211; Inscription en Ligne uniquement : date limite le 28\/02\/2019 &#8211; Droit d\u2019inscription athl\u00e8te : joindre au r\u00e8glement (ch\u00e8que club), soit la copie de votre saisie sur l\u2019intranet OU le fichier excel ci-joint. Le [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2659","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts\/2659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/comments?post=2659"}],"version-history":[{"count":0,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts\/2659\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/media?parent=2659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/categories?post=2659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/tags?post=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}