{"id":601,"date":"2016-03-23T14:42:48","date_gmt":"2016-03-23T13:42:48","guid":{"rendered":"https:\/\/sites.ffkarate.fr\/normandie\/?post_type=news&amp;p=601"},"modified":"2016-03-23T14:42:48","modified_gmt":"2016-03-23T13:42:48","slug":"actualites-mardi-23-mars-2016","status":"publish","type":"post","link":"https:\/\/sites.ffkarate.fr\/normandie\/2016\/03\/23\/actualites-mardi-23-mars-2016\/","title":{"rendered":"Actualit\u00e9s \u2013 Mardi 23 Mars 2016"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Deux nouveaux stages sont disponibles, nous vous invitons \u00e0 en prendre connaissance dans la section <a href=\"https:\/\/sites.ffkarate.fr\/normandie\/stages\/\">Stages de Karat\u00e9<\/a>, et \u00e0 diffuser ces informations dans vos dojos.<\/p>\n<p><strong>Samedi 16 avril 2016 &#8211; Stage Formation et Recyclage Jurys Grades<\/strong><br \/>\n<strong>Samedi 16 avril 2016 &#8211; Stage d&rsquo;informations passage de grades<\/strong><br \/>\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Deux nouveaux stages sont disponibles, nous vous invitons \u00e0 en prendre connaissance dans la section Stages de Karat\u00e9, et \u00e0 diffuser ces informations dans vos dojos. Samedi 16 avril 2016 &#8211; Stage Formation et Recyclage Jurys Grades Samedi 16 avril 2016 &#8211; Stage d&rsquo;informations passage de grades [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":57,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-601","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts\/601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/comments?post=601"}],"version-history":[{"count":0,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/posts\/601\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/media?parent=601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/categories?post=601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ffkarate.fr\/normandie\/wp-json\/wp\/v2\/tags?post=601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}